{"id":522,"date":"2015-11-18T17:07:00","date_gmt":"2015-11-18T17:07:00","guid":{"rendered":"http:\/\/devwgst.cah.ucf.edu\/?p=522"},"modified":"2016-02-18T20:06:08","modified_gmt":"2016-02-18T20:06:08","slug":"wgst-student-wins-hispanic-heritage-scholarship","status":"publish","type":"news","link":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/","title":{"rendered":"WGST Student Wins Hispanic Heritage Scholarship"},"content":{"rendered":"<div class=\"highlightentry\">\n<p>Women\u2019s and Gender Studies is happy to announce that Daniela Mui\u00f1o, a junior student minoring in the program, was selected to receive the prestigious $5,000 Hispanic Heritage Scholarship.<\/p>\n<p>Mui\u00f1o is from Miami, Florida and plans to graduate in 2018. She is very proud of her Latino roots and what it means to receive this recognition. Currently, Mui\u00f1o is a facilitator with the Young Women Leaders Program and a member of MSC Pride Coalition\u2019s Committee for AY 2014-2015.<\/p>\n<p>\u201cIt feels amazing to have been selected for this award, not only because I was recognized as an exceptional student, but also as an exceptional Latina student. It makes me feel like I am exceptional not despite my heritage, but because of my heritage, because of where I come from, and because of who I am. I want everyone who has ever been marginalized by others to feel this way \u2013 it\u2019s my ultimate goal in life,&#8221; says Mui\u00f1o.<\/p>\n<p>On becoming an animator, Mui\u00f1o stated: &#8220;I want to reach those who I can\u2019t physically reach and tell them that they can, that they\u2019re beautiful, and that they\u2019re valid, no matter who they are or where they come from. I want to tell the stories that aren\u2019t told, and I want young queer girls and girls of color to find themselves in the media I make for them.&#8221;\u00a0Mui\u00f1o closed with, &#8220;what I\u2019ve learned in this amazing department has given me the knowledge I need to create meaningful work, as well as giving me the courage and support to pursue my lifelong goals.\u201d<\/p>\n<p>The Hispanic Heritage Scholarship is the highest accolade\u00a0in Orlando for Latino students. The Hispanic Heritage Scholarship Fund of Metro Orlando, which provided the scholarship, is the largest non-profit organization in Central Florida dedicated to providing scholarships to Hispanic students pursuing a college or university degree. They have a mission to support the college education goals and development of outstanding Hispanic students in Central Florida.<\/p>\n<p>For more information about the award, you can navigate to the <a href=\"http:\/\/hispanicheritagescholarshipfund.org\/\" target=\"_blank\" rel=\"external\">Hispanic Heritage Scholarship Fund of Metro Orlando website<\/a>.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Women\u2019s and Gender Studies is happy to announce that Daniela Mui\u00f1o, a junior student minoring in the program, was selected to receive the prestigious $5,000 Hispanic Heritage Scholarship. Mui\u00f1o is from Miami, Florida and plans to graduate in 2018. She is very proud of her Latino roots and what it means to receive this recognition.&hellip;","protected":false},"author":"","featured_media":"https:\/\/cah.ucf.edu\/womengender\/wp-content\/uploads\/sites\/26\/2015\/11\/1498.jpg","template":"","categories":[3,1],"tags":[],"dept":[],"class_list":["post-522","news","type-news","status-publish","has-post-thumbnail","hentry","category-highlight","category-uncategorized"],"acf":[],"approved":0,"site_name":"Women&#039;s and Gender\u00a0Studies","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WGST Student Wins Hispanic Heritage Scholarship - Women&#039;s and Gender\u00a0Studies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WGST Student Wins Hispanic Heritage Scholarship - Women&#039;s and Gender\u00a0Studies\" \/>\n<meta property=\"og:description\" content=\"Women\u2019s and Gender Studies is happy to announce that Daniela Mui\u00f1o, a junior student minoring in the program, was selected to receive the prestigious $5,000 Hispanic Heritage Scholarship. Mui\u00f1o is from Miami, Florida and plans to graduate in 2018. She is very proud of her Latino roots and what it means to receive this recognition.&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/\" \/>\n<meta property=\"og:site_name\" content=\"Women&#039;s and Gender\u00a0Studies\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-18T20:06:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cah.ucf.edu\/womengender\/wp-content\/uploads\/sites\/26\/2015\/11\/1498.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/news\\\/wgst-student-wins-hispanic-heritage-scholarship\\\/\",\"url\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/news\\\/wgst-student-wins-hispanic-heritage-scholarship\\\/\",\"name\":\"WGST Student Wins Hispanic Heritage Scholarship - Women&#039;s and Gender\u00a0Studies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/news\\\/wgst-student-wins-hispanic-heritage-scholarship\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/news\\\/wgst-student-wins-hispanic-heritage-scholarship\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/11\\\/1498.jpg\",\"datePublished\":\"2015-11-18T17:07:00+00:00\",\"dateModified\":\"2016-02-18T20:06:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/news\\\/wgst-student-wins-hispanic-heritage-scholarship\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/news\\\/wgst-student-wins-hispanic-heritage-scholarship\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/news\\\/wgst-student-wins-hispanic-heritage-scholarship\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/11\\\/1498.jpg\",\"contentUrl\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/wp-content\\\/uploads\\\/sites\\\/26\\\/2015\\\/11\\\/1498.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/news\\\/wgst-student-wins-hispanic-heritage-scholarship\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WGST Student Wins Hispanic Heritage Scholarship\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/#website\",\"url\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/\",\"name\":\"Women&#039;s and Gender\u00a0Studies\",\"description\":\"Women&#039;s and Gender Studies program at the University of Central Florida\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cah.ucf.edu\\\/womengender\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WGST Student Wins Hispanic Heritage Scholarship - Women&#039;s and Gender\u00a0Studies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/","og_locale":"en_US","og_type":"article","og_title":"WGST Student Wins Hispanic Heritage Scholarship - Women&#039;s and Gender\u00a0Studies","og_description":"Women\u2019s and Gender Studies is happy to announce that Daniela Mui\u00f1o, a junior student minoring in the program, was selected to receive the prestigious $5,000 Hispanic Heritage Scholarship. Mui\u00f1o is from Miami, Florida and plans to graduate in 2018. She is very proud of her Latino roots and what it means to receive this recognition.&hellip;","og_url":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/","og_site_name":"Women&#039;s and Gender\u00a0Studies","article_modified_time":"2016-02-18T20:06:08+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/cah.ucf.edu\/womengender\/wp-content\/uploads\/sites\/26\/2015\/11\/1498.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/","url":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/","name":"WGST Student Wins Hispanic Heritage Scholarship - Women&#039;s and Gender\u00a0Studies","isPartOf":{"@id":"https:\/\/cah.ucf.edu\/womengender\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/#primaryimage"},"image":{"@id":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/#primaryimage"},"thumbnailUrl":"https:\/\/cah.ucf.edu\/womengender\/wp-content\/uploads\/sites\/26\/2015\/11\/1498.jpg","datePublished":"2015-11-18T17:07:00+00:00","dateModified":"2016-02-18T20:06:08+00:00","breadcrumb":{"@id":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/#primaryimage","url":"https:\/\/cah.ucf.edu\/womengender\/wp-content\/uploads\/sites\/26\/2015\/11\/1498.jpg","contentUrl":"https:\/\/cah.ucf.edu\/womengender\/wp-content\/uploads\/sites\/26\/2015\/11\/1498.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/cah.ucf.edu\/womengender\/news\/wgst-student-wins-hispanic-heritage-scholarship\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cah.ucf.edu\/womengender\/"},{"@type":"ListItem","position":2,"name":"WGST Student Wins Hispanic Heritage Scholarship"}]},{"@type":"WebSite","@id":"https:\/\/cah.ucf.edu\/womengender\/#website","url":"https:\/\/cah.ucf.edu\/womengender\/","name":"Women&#039;s and Gender\u00a0Studies","description":"Women&#039;s and Gender Studies program at the University of Central Florida","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cah.ucf.edu\/womengender\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/news\/522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/types\/news"}],"author":[{"embeddable":true,"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":4,"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/news\/522\/revisions"}],"predecessor-version":[{"id":786,"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/news\/522\/revisions\/786"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/media\/523"}],"wp:attachment":[{"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/media?parent=522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/categories?post=522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/tags?post=522"},{"taxonomy":"dept","embeddable":true,"href":"https:\/\/cah.ucf.edu\/womengender\/wp-json\/wp\/v2\/dept?post=522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}