{"id":2119,"date":"2017-08-14T19:42:15","date_gmt":"2017-08-14T19:42:15","guid":{"rendered":"https:\/\/floridareview.cah.ucf.edu\/article\/what-we-keep\/"},"modified":"2017-08-14T19:42:15","modified_gmt":"2017-08-14T19:42:15","slug":"what-we-keep","status":"publish","type":"article","link":"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/","title":{"rendered":"What We Keep"},"content":{"rendered":"<p>This article is a stub.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>This article is a stub.<\/p>\n","protected":false},"featured_media":0,"template":"","categories":[307,142],"tags":[8],"class_list":["post-2119","article","type-article","status-publish","hentry","category-florida-review","category-nonfiction","tag-the-florida-review"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>What We Keep - The Florida Review<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"What We Keep - The Florida Review\" \/>\n<meta property=\"og:description\" content=\"This article is a stub.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/\" \/>\n<meta property=\"og:site_name\" content=\"The Florida Review\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/article\\\/what-we-keep\\\/\",\"url\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/article\\\/what-we-keep\\\/\",\"name\":\"What We Keep - The Florida Review\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/#website\"},\"datePublished\":\"2017-08-14T19:42:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/article\\\/what-we-keep\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/article\\\/what-we-keep\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/article\\\/what-we-keep\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"What We Keep\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/#website\",\"url\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/\",\"name\":\"The Florida Review\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cah.ucf.edu\\\/floridareview\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"What We Keep - The Florida Review","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/","og_locale":"en_US","og_type":"article","og_title":"What We Keep - The Florida Review","og_description":"This article is a stub.","og_url":"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/","og_site_name":"The Florida Review","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/","url":"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/","name":"What We Keep - The Florida Review","isPartOf":{"@id":"https:\/\/cah.ucf.edu\/floridareview\/#website"},"datePublished":"2017-08-14T19:42:15+00:00","breadcrumb":{"@id":"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cah.ucf.edu\/floridareview\/article\/what-we-keep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cah.ucf.edu\/floridareview\/"},{"@type":"ListItem","position":2,"name":"What We Keep"}]},{"@type":"WebSite","@id":"https:\/\/cah.ucf.edu\/floridareview\/#website","url":"https:\/\/cah.ucf.edu\/floridareview\/","name":"The Florida Review","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cah.ucf.edu\/floridareview\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/cah.ucf.edu\/floridareview\/wp-json\/wp\/v2\/article\/2119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cah.ucf.edu\/floridareview\/wp-json\/wp\/v2\/article"}],"about":[{"href":"https:\/\/cah.ucf.edu\/floridareview\/wp-json\/wp\/v2\/types\/article"}],"version-history":[{"count":0,"href":"https:\/\/cah.ucf.edu\/floridareview\/wp-json\/wp\/v2\/article\/2119\/revisions"}],"wp:attachment":[{"href":"https:\/\/cah.ucf.edu\/floridareview\/wp-json\/wp\/v2\/media?parent=2119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cah.ucf.edu\/floridareview\/wp-json\/wp\/v2\/categories?post=2119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cah.ucf.edu\/floridareview\/wp-json\/wp\/v2\/tags?post=2119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}